{"id":3336,"date":"2017-09-20T14:07:21","date_gmt":"2017-09-20T14:07:21","guid":{"rendered":"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/"},"modified":"2017-11-17T15:29:18","modified_gmt":"2017-11-17T15:29:18","slug":"mas-informacion-sobre-las-cookies","status":"publish","type":"page","link":"http:\/\/josefelixvaldivieso.com\/en\/mas-informacion-sobre-las-cookies\/","title":{"rendered":"M\u00e1s informaci\u00f3n sobre las cookies"},"content":{"rendered":"<h2>\u00bfQu\u00e9 es una cookie?<\/h2>\n<p>Una <em>cookie<\/em> es un fichero de texto <b>inofensivo<\/b> que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. La utilidad de la <em>cookie<\/em> es que la web sea capaz de recordar su visita cuando vuelva a navegar por esa p\u00e1gina. Aunque mucha gente no lo sabe las <em>cookies<\/em> se llevan utilizando desde hace 20 a\u00f1os, cuando aparecieron los primeros navegadores para la World Wide Web.<\/p>\n<h2>\u00bfQu\u00e9 NO ES una cookie?<\/h2>\n<p>No es un virus, ni un troyano, ni un gusano, ni spam, ni spyware, ni abre ventanas pop-up.<\/p>\n<h2>\u00bfQu\u00e9 informaci\u00f3n almacena una <em>cookie<\/em>?<\/h2>\n<p>Las <em>cookies<\/em> no suelen almacenar informaci\u00f3n sensible sobre usted, como tarjetas de cr\u00e9dito o datos bancarios, fotograf\u00edas, su DNI o informaci\u00f3n personal, etc. Los datos que guardan son de car\u00e1cter t\u00e9cnico, preferencias personales, personalizaci\u00f3n de contenidos, etc.<\/p>\n<p>El servidor web no le asocia a usted como persona si no a su navegador web. De hecho, si usted navega habitualmente con Internet Explorer y prueba a navegar por la misma web con Firefox o Chrome ver\u00e1 que la web no se da cuenta que es usted la misma persona porque en realidad est\u00e1 asociando al navegador, no a la persona.<\/p>\n<h2>\u00bfQu\u00e9 tipo de <em>cookies<\/em> existen?<\/h2>\n<ul>\n<li><em>Cookies<\/em> t\u00e9cnicas: Son las m\u00e1s elementales y permiten, entre otras cosas, saber cu\u00e1ndo est\u00e1 navegando un humano o una aplicaci\u00f3n automatizada, cu\u00e1ndo navega un usuario an\u00f3nimo y uno registrado, tareas b\u00e1sicas para el funcionamiento de cualquier web din\u00e1mica.<\/li>\n<li><em>Cookies<\/em> de an\u00e1lisis: Recogen informaci\u00f3n sobre el tipo de navegaci\u00f3n que est\u00e1 realizando, las secciones que m\u00e1s utiliza, productos consultados, franja horaria de uso, idioma, etc.<\/li>\n<li><em>Cookies<\/em> publicitarias: Muestran publicidad en funci\u00f3n de su navegaci\u00f3n, su pa\u00eds de procedencia, idioma, etc.<\/li>\n<\/ul>\n<h2>\u00bfQu\u00e9 son las <em>cookies<\/em> propias y las de terceros?<\/h2>\n<p>Las <em>cookies propias<\/em> son las generadas por la p\u00e1gina que est\u00e1 visitando y las <em>de terceros<\/em> son las generadas por servicios o proveedores externos como Facebook, Twitter, Google, etc.<\/p>\n<h2>\u00bfQu\u00e9 ocurre si desactivo las <em>cookies<\/em>?<\/h2>\n<p>Para que entienda el alcance que puede tener desactivar las <em>cookies<\/em> le mostramos unos ejemplos:<\/p>\n<ul>\n<li>No podr\u00e1 compartir contenidos de esa web en Facebook, Twitter o cualquier otra red social.<\/li>\n<li>El sitio web no podr\u00e1 adaptar los contenidos a sus preferencias personales, como suele ocurrir en las tiendas online.<\/li>\n<li>No podr\u00e1 acceder al \u00e1rea personal de esa web, como por ejemplo <em>Mi cuenta<\/em>, o <em>Mi perfil<\/em> o <em>Mis pedidos<\/em>.<\/li>\n<li>Tiendas online: Le ser\u00e1 imposible realizar compras online, tendr\u00e1n que ser telef\u00f3nicas o visitando la tienda f\u00edsica si es que dispone de ella.<\/li>\n<li>No ser\u00e1 posible personalizar sus preferencias geogr\u00e1ficas como franja horaria, divisa o idioma.<\/li>\n<li>El sitio web no podr\u00e1 realizar anal\u00edticas web sobre visitantes y tr\u00e1fico en la web, lo que dificultar\u00e1 que la web sea competitiva.<\/li>\n<li>No podr\u00e1 escribir en el blog, no podr\u00e1 subir fotos, publicar comentarios, valorar o puntuar contenidos. La web tampoco podr\u00e1 saber si usted es un humano o una aplicaci\u00f3n automatizada que publica <em>spam<\/em>.<\/li>\n<li>No se podr\u00e1 mostrar publicidad sectorizada, lo que reducir\u00e1 los ingresos publicitarios de la web.<\/li>\n<li>Todas las redes sociales usan <em>cookies<\/em>, si las desactiva no podr\u00e1 utilizar ninguna red social.<\/li>\n<\/ul>\n<h2>\u00bfSe pueden eliminar las <em>cookies<\/em>?<\/h2>\n<p>S\u00ed. No s\u00f3lo eliminar, tambi\u00e9n bloquear, de forma general o particular para un dominio espec\u00edfico.<\/p>\n<p>Para eliminar las <em>cookies<\/em> de un sitio web debe ir a la configuraci\u00f3n de su navegador y all\u00ed podr\u00e1 buscar las asociadas al dominio en cuesti\u00f3n y proceder a su eliminaci\u00f3n.<\/p>\n<h2 id=\"navegadores\">Configuraci\u00f3n de <em>cookies<\/em> para los navegadores m\u00e1s polulares<\/h2>\n<p>A continuaci\u00f3n le indicamos c\u00f3mo acceder a una <em>cookie<\/em> determinada del navegador <b>Chrome<\/b>. Nota: estos pasos pueden variar en funci\u00f3n de la versi\u00f3n del navegador:<\/p>\n<ol>\n<li>Vaya a Configuraci\u00f3n o Preferencias mediante el men\u00fa Archivo o bien pinchando el icono de personalizaci\u00f3n que aparece arriba a la derecha.<\/li>\n<li>Ver\u00e1 diferentes secciones, pinche la opci\u00f3n <em>Mostrar opciones avanzadas<\/em>.<\/li>\n<li>Vaya a <em>Privacidad<\/em>, <em>Configuraci\u00f3n de contenido<\/em>.<\/li>\n<li>Seleccione <em>Todas las <em>cookies<\/em> y los datos de sitios<\/em>.<\/li>\n<li>Aparecer\u00e1 un listado con todas las <em>cookies<\/em> ordenadas por dominio. Para que le sea m\u00e1s f\u00e1cil encontrar las <em>cookies<\/em> de un determinado dominio introduzca parcial o totalmente la direcci\u00f3n en el campo <em>Buscar cookies<\/em>.<\/li>\n<li>Tras realizar este filtro aparecer\u00e1n en pantalla una o varias l\u00edneas con las <em>cookies<\/em> de la web solicitada. Ahora s\u00f3lo tiene que seleccionarla y pulsar la <em>X<\/em> para proceder a su eliminaci\u00f3n.<\/li>\n<\/ol>\n<p>Para acceder a la configuraci\u00f3n de <em>cookies<\/em> del navegador <b>Internet Explorer<\/b> siga estos pasos (pueden variar en funci\u00f3n de la versi\u00f3n del navegador):<\/p>\n<ol>\n<li>Vaya a <em>Herramientas<\/em>, <em>Opciones de Internet<\/em><\/li>\n<li>Haga click en <em>Privacidad<\/em>.<\/li>\n<li>Mueva el deslizador hasta ajustar el nivel de privacidad que desee.<\/li>\n<\/ol>\n<p>Para acceder a la configuraci\u00f3n de <em>cookies<\/em> del navegador <b>Firefox<\/b> siga estos pasos (pueden variar en funci\u00f3n de la versi\u00f3n del navegador):<\/p>\n<ol>\n<li>Vaya a <em>Opciones<\/em> o <em>Preferencias<\/em> seg\u00fan su sistema operativo.<\/li>\n<li>Haga click en <em>Privacidad<\/em>.<\/li>\n<li>En <em>Historial<\/em> elija <em>Usar una configuraci\u00f3n personalizada para el historial<\/em>.<\/li>\n<li>Ahora ver\u00e1 la opci\u00f3n <em>Aceptar cookies<\/em>, puede activarla o desactivarla seg\u00fan sus preferencias.<\/li>\n<\/ol>\n<p>Para acceder a la configuraci\u00f3n de <em>cookies<\/em> del navegador <b>Safari para OSX<\/b> siga estos pasos (pueden variar en funci\u00f3n de la versi\u00f3n del navegador):<\/p>\n<ol>\n<li>Vaya a <em>Preferencias<\/em>, luego <em>Privacidad<\/em>.<\/li>\n<li>En este lugar ver\u00e1 la opci\u00f3n <em>Bloquear cookies<\/em> para que ajuste el tipo de bloqueo que desea realizar.<\/li>\n<\/ol>\n<p>Para acceder a la configuraci\u00f3n de <em>cookies<\/em> del navegador <b>Safari para iOS<\/b> siga estos pasos (pueden variar en funci\u00f3n de la versi\u00f3n del navegador):<\/p>\n<ol>\n<li>Vaya a <em>Ajustes<\/em>, luego <em>Safari<\/em>.<\/li>\n<li>Vaya a <em>Privacidad y Seguridad<\/em>, ver\u00e1 la opci\u00f3n <em>Bloquear cookies<\/em> para que ajuste el tipo de bloqueo que desea realizar.<\/li>\n<\/ol>\n<p>Para acceder a la configuraci\u00f3n de <em>cookies<\/em> del navegador para dispositivos <b>Android<\/b> siga estos pasos (pueden variar en funci\u00f3n de la versi\u00f3n del navegador):<\/p>\n<ol>\n<li>Ejecute el navegador y pulse la tecla <em>Men\u00fa<\/em>, luego <em>Ajustes<\/em>.<\/li>\n<li>Vaya a <em>Seguridad y Privacidad<\/em>, ver\u00e1 la opci\u00f3n <em>Aceptar cookies<\/em> para que active o desactive la casilla.<\/li>\n<\/ol>\n<p>Para acceder a la configuraci\u00f3n de <em>cookies<\/em> del navegador para dispositivos <b>Windows Phone<\/b> siga estos pasos (pueden variar en funci\u00f3n de la versi\u00f3n del navegador):<\/p>\n<ol>\n<li>Abra <em>Internet Explorer<\/em>, luego <em>M\u00e1s<\/em>, luego <em>Configuraci\u00f3n<\/em><\/li>\n<li>Ahora puede activar o desactivar la casilla <em>Permitir cookies<\/em>.<\/li>\n<\/ol>\n<p>Asesor de Cookies es un <a href=\"http:\/\/wordpress.org\/plugins\/asesor-cookies-para-la-ley-en-espana\/\" target=\"_blank\" rel=\"noopener\">plugin para WordPress<\/a> creado por Carlos Doral (<a href=\"http:\/\/webartesanal.com\" target=\"_blank\" rel=\"noopener\">webartesanal.com<\/a>)<\/p>\n","protected":false},"excerpt":{"rendered":"<p>\u00bfQu\u00e9 es una cookie? Una cookie es un fichero de texto inofensivo que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. La utilidad de la cookie es&#8230;<\/p>\n","protected":false},"author":1,"featured_media":0,"parent":0,"menu_order":0,"comment_status":"closed","ping_status":"closed","template":"","meta":{"footnotes":""},"class_list":["post-3336","page","type-page","status-publish"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>M\u00e1s informaci\u00f3n sobre las cookies<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/\" \/>\n<meta property=\"og:locale\" content=\"en_US\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"M\u00e1s informaci\u00f3n sobre las cookies\" \/>\n<meta property=\"og:description\" content=\"\u00bfQu\u00e9 es una cookie? Una cookie es un fichero de texto inofensivo que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. La utilidad de la cookie es...\" \/>\n<meta property=\"og:url\" content=\"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/\" \/>\n<meta property=\"og:site_name\" content=\"Jos\u00e9 F\u00e9lix Valdivieso\" \/>\n<meta property=\"article:modified_time\" content=\"2017-11-17T15:29:18+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:label1\" content=\"Est. reading time\" \/>\n\t<meta name=\"twitter:data1\" content=\"6 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/mas-informacion-sobre-las-cookies\\\/\",\"url\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/mas-informacion-sobre-las-cookies\\\/\",\"name\":\"M\u00e1s informaci\u00f3n sobre las cookies\",\"isPartOf\":{\"@id\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/en\\\/#website\"},\"datePublished\":\"2017-09-20T14:07:21+00:00\",\"dateModified\":\"2017-11-17T15:29:18+00:00\",\"breadcrumb\":{\"@id\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/mas-informacion-sobre-las-cookies\\\/#breadcrumb\"},\"inLanguage\":\"en-US\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"http:\\\/\\\/josefelixvaldivieso.com\\\/mas-informacion-sobre-las-cookies\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/mas-informacion-sobre-las-cookies\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/en\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"M\u00e1s informaci\u00f3n sobre las cookies\"}]},{\"@type\":\"WebSite\",\"@id\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/en\\\/#website\",\"url\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/en\\\/\",\"name\":\"Jos\u00e9 F\u00e9lix Valdivieso\",\"description\":\"Blog de Autor\",\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"http:\\\/\\\/josefelixvaldivieso.com\\\/en\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"en-US\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"M\u00e1s informaci\u00f3n sobre las cookies","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/","og_locale":"en_US","og_type":"article","og_title":"M\u00e1s informaci\u00f3n sobre las cookies","og_description":"\u00bfQu\u00e9 es una cookie? Una cookie es un fichero de texto inofensivo que se almacena en su navegador cuando visita casi cualquier p\u00e1gina web. La utilidad de la cookie es...","og_url":"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/","og_site_name":"Jos\u00e9 F\u00e9lix Valdivieso","article_modified_time":"2017-11-17T15:29:18+00:00","twitter_card":"summary_large_image","twitter_misc":{"Est. reading time":"6 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/","url":"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/","name":"M\u00e1s informaci\u00f3n sobre las cookies","isPartOf":{"@id":"http:\/\/josefelixvaldivieso.com\/en\/#website"},"datePublished":"2017-09-20T14:07:21+00:00","dateModified":"2017-11-17T15:29:18+00:00","breadcrumb":{"@id":"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/#breadcrumb"},"inLanguage":"en-US","potentialAction":[{"@type":"ReadAction","target":["http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/"]}]},{"@type":"BreadcrumbList","@id":"http:\/\/josefelixvaldivieso.com\/mas-informacion-sobre-las-cookies\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"http:\/\/josefelixvaldivieso.com\/en\/"},{"@type":"ListItem","position":2,"name":"M\u00e1s informaci\u00f3n sobre las cookies"}]},{"@type":"WebSite","@id":"http:\/\/josefelixvaldivieso.com\/en\/#website","url":"http:\/\/josefelixvaldivieso.com\/en\/","name":"Jos\u00e9 F\u00e9lix Valdivieso","description":"Blog de Autor","potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"http:\/\/josefelixvaldivieso.com\/en\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"en-US"}]}},"_links":{"self":[{"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/pages\/3336","targetHints":{"allow":["GET"]}}],"collection":[{"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/pages"}],"about":[{"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/types\/page"}],"author":[{"embeddable":true,"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/comments?post=3336"}],"version-history":[{"count":1,"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/pages\/3336\/revisions"}],"predecessor-version":[{"id":3475,"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/pages\/3336\/revisions\/3475"}],"wp:attachment":[{"href":"http:\/\/josefelixvaldivieso.com\/en\/wp-json\/wp\/v2\/media?parent=3336"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}